{"id":194,"date":"2016-02-15T23:00:39","date_gmt":"2016-02-15T23:00:39","guid":{"rendered":"https:\/\/sandbox.favethemes.com\/houzez\/?page_id=194"},"modified":"2025-05-29T08:29:54","modified_gmt":"2025-05-29T12:29:54","slug":"homepage-with-map","status":"publish","type":"page","link":"https:\/\/globoplus.com\/cl\/","title":{"rendered":"Homepage"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"194\" class=\"elementor elementor-194\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1d7965 elementor-section-height-full elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"c1d7965\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a552e5c\" data-id=\"a552e5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cff6ff elementor-widget elementor-widget-spacer\" data-id=\"9cff6ff\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac6cf9b animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"ac6cf9b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Simplificamos la b\u00fasqueda de tu nuevo hogar<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">Transform\u00e1ndola en una experiencia simple y libre de estr\u00e9s.<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-590db8a elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"590db8a\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c702c90 animated-slow elementor-hidden-desktop elementor-hidden-tablet elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"c702c90\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">\u00bfEn qu\u00e9 te podemos ayudar hoy?<\/h2>\n                \n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc57463 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"fc57463\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-153e753 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"153e753\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bdcd580\" data-id=\"bdcd580\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9a5d36 elementor-widget elementor-widget-html\" data-id=\"d9a5d36\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe\n    style=\"height: 550px; width: 1000px; border: none;\"\n        src=\"https:\/\/cdn.botpress.cloud\/webchat\/v2.5\/shareable.html?configUrl=https:\/\/files.bpcontent.cloud\/2025\/05\/13\/03\/20250513030053-U3DT1MGU.json\"\n        ><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-66a4f76 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66a4f76\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ef0ff3d\" data-id=\"ef0ff3d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-08f7f53\" data-id=\"08f7f53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7a7e04 elementor-button-success elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e7a7e04\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\" id=\"toggle-chatbot\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Abrir GloboChat<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8d02846\" data-id=\"8d02846\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5ca71bc elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ca71bc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9d860d6\" data-id=\"9d860d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d140b82 elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"d140b82\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b4e67dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4e67dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-49ad3f2\" data-id=\"49ad3f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70df375 animated-slow elementor-button-align-stretch elementor-invisible elementor-widget elementor-widget-houzez_elementor_search_builder\" data-id=\"70df375\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_search_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <form class=\"houzez-search-form-js houzez-search-builder-form-js\" id=\"houzez-search-70df375\" method=\"get\" action=\"https:\/\/globoplus.com\/cl\/index.php\/search-results\/\" >\n\n            \n            <ul id=\"houzez-search-tabs-wrap\" class=\"houzez-status-tabs nav nav-pills\" role=\"tablist\" data-toggle=\"buttons\">\n            \n                                <li class=\"nav-item\">\n                    <a class=\"nav-link active\" data-val=\"\" data-toggle=\"pill\" href=\"#\" role=\"tab\" aria-selected=\"true\">\n                        All                    <\/a>\n                <\/li>\n                \n                <li class=\"nav-item\">\n                                <a class=\"status-tab-js nav-link \" data-val=\"for-rent\" data-toggle=\"pill\" href=\"#\" role=\"tab\" aria-selected=\"true\">\n                                    En Arriendo\n                                <\/a>\n                            <\/li><li class=\"nav-item\">\n                                <a class=\"status-tab-js nav-link \" data-val=\"for-sale\" data-toggle=\"pill\" href=\"#\" role=\"tab\" aria-selected=\"true\">\n                                    En Venta\n                                <\/a>\n                            <\/li>                <input type=\"hidden\" name=\"status[]\" id=\"search-tabs\" value=\"\">\n            <\/ul>\n            \n            <div class=\"houzez-ele-search-form-wrapper elementor-form-fields-wrapper elementor-labels-above\">\n\n                                        <div class=\"elementor-field-group elementor-column form-group elementor-field-group-field-cities elementor-col-20\">\n                    <label for=\"form-field-field-cities\" class=\"elementor-field-label elementor-screen-only\">Barrios<\/label>        <div class=\"elementor-field elementor-select-wrapper\">\n            <select data-size=\"5\" name=\"areas[]\" id=\"form-field-field-cities\" class=\"selectpicker bs-select-hidden houzez-field-textual form-control elementor-size-md houzezSelectFilter houzezFourthList\" data-none-results-text=\"Ning\u00fan resultado coincide {0}\">\n                <option value=\"\">Barrios<\/option><option data-ref=\"asuncion-capital\" data-belong=\"asuncion\" data-subtext=\"Asunci\u00f3n\" value=\"asuncion-capital\">Asunci\u00f3n Capital<\/option>            <\/select>\n        <\/div>\n                            <\/div>\n                    \n                                            <div class=\"elementor-field-group elementor-column form-group elementor-field-group-1ba3a4c elementor-col-60\">\n                    <label for=\"form-field-1ba3a4c\" class=\"elementor-field-label elementor-screen-only\">Palabra clave<\/label><input type=\"text\" size=\"1\" name=\"keyword\" id=\"form-field-1ba3a4c\" value=\"\" class=\"elementor-field form-control elementor-size-md elementor-field-textual houzez-keyword-autocomplete\" placeholder=\"Ingresa  el texto...\"><div id=\"auto_complete_ajax\" class=\"auto-complete\"><\/div>                    <\/div>\n                    \n                                                <div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-20\">\n                                <button type=\"submit\" class=\"houzez-search-button elementor-button elementor-size-md\">\n                                                                            Buscar                                                                    <\/button>\n                            <\/div>\n                            \n                    \n            <\/div><!-- End wrapper-->\n\n        <\/form>\n\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a4ba4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a4ba4e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e5814e\" data-id=\"5e5814e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-130d89e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"130d89e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d1fa245\" data-id=\"d1fa245\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92ea348 elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"92ea348\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c46e30 animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"2c46e30\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Propiedades Destacadas<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">Descubre los proyectos inmobiliarios en Paraguay donde tu inversi\u00f3n crece con seguridad, transparencia y visi\u00f3n a futuro.<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac777fb elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"ac777fb\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5811ff4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5811ff4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2b0e81\" data-id=\"d2b0e81\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52f81fd animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_property-card-v5\" data-id=\"52f81fd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_property-card-v5.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t<div id=\"properties_module_section\" class=\"property-cards-module property-cards-module-v1 property-cards-module-3-cols\">\r\n\t\t\t<div id=\"module_properties\" class=\"listing-view grid-view card-deck grid-view-3-cols\">\r\n\t\t\t\t<div class=\"col-lg-12\">\n\t<p class=\"mt-30 text-center\">\n\t\tNo hemos encontrado ning\u00fan anuncio.\t<\/p>\n<\/div>\r\n\t\t\t<\/div><!-- listing-view -->\r\n\r\n\t\t\t\t\t\t\t<div id=\"fave-pagination-loadmore\" class=\"load-more-wrap mb-4 fave-load-more\">\r\n                    <a class=\"btn btn-primary-outlined btn-load-more\"  \r\n                    data-paged=\"2\" \r\n                    data-prop-limit=\"6\" \r\n                    data-card=\"item-v5\" \r\n                    data-type=\"\" \r\n                    data-status=\"\" \r\n                    data-state=\"\" \r\n                    data-city=\"\" \r\n                    data-country=\"\" \r\n                    data-area=\"\" \r\n                    data-label=\"\" \r\n                    data-user-role=\"\" \r\n                    data-featured-prop=\"yes\" \r\n                    data-offset=\"\"\r\n                    data-sortby=\"\"\r\n                    data-property_ids=\"\"\r\n                    data-min_price=\"\"\r\n                    data-max_price=\"\"\r\n                    data-min_beds=\"\"\r\n                    data-max_beds=\"\"\r\n                    data-min_baths=\"\"\r\n                    data-max_baths=\"\"\r\n                    data-agents=\"\"\r\n                    data-agencies=\"\"\r\n                    data-post_status=\"all\"\r\n                    href=\"#\">\r\n                    \t<span class=\"btn-loader houzez-loader-js\"><\/span>                    \tCarga m\u00e1s\t\t\r\n                    <\/a>               \r\n\t\t\t\t<\/div><!-- load-more-wrap -->\r\n\t\t\t\t\t<\/div><!-- property-grid-module -->\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0498b16 elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"0498b16\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c01f788 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"c01f788\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:1592,&quot;url&quot;:&quot;https:\\\/\\\/demo05.houzez.co\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/houzez-header-1.jpg&quot;},{&quot;id&quot;:1608,&quot;url&quot;:&quot;https:\\\/\\\/demo05.houzez.co\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/houzez-property-slider.jpg&quot;},{&quot;id&quot;:1604,&quot;url&quot;:&quot;https:\\\/\\\/demo05.houzez.co\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/houzez-header-2.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:3000,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5cf4e6\" data-id=\"e5cf4e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ecec099 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ecec099\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-00217b0 elementor-invisible\" data-id=\"00217b0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8273ae5 elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"8273ae5\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Inversi\u00f3n inteligente en un mercado en expansi\u00f3n<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">Una oportunidad clara de ingreso estable y sostenido, con bajo nivel de riesgo y alto potencial de crecimiento.<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-925faea elementor-widget elementor-widget-button\" data-id=\"925faea\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descubre+<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-6c2aa0c\" data-id=\"6c2aa0c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-921656b elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"921656b\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9eb82e7\" data-id=\"9eb82e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41439d4 elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"41439d4\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff797c4 animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"ff797c4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Explora Por Barrio<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">HAY DIFERENTES OPCIONES DE PROPIEDADES PARA ELEGIR, CADA UNA CON UN PROP\u00d3SITO Y ENFOQUE A DISTINTOS TIPOS DE PUBLICO OBJETIVO<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d3383c elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"5d3383c\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f28f10f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f28f10f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed08a7c\" data-id=\"ed08a7c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8d2e672 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d2e672\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b13cd7a\" data-id=\"b13cd7a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50c3c91 animated-slow elementor-invisible elementor-widget elementor-widget-Houzez_elementor_grid_builder\" data-id=\"50c3c91\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"Houzez_elementor_grid_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"grid-item  grid-item-v2\" style=\"background-image: url(https:\/\/globoplus.com\/cl\/wp-includes\/images\/media\/default.svg)\">\n            <a class=\"grid-item-link hover-effect-flat\"  href=\"https:\/\/globoplus.com\/cl\/index.php\/area\/laguna-grande\/\">\n                <div class=\"grid-item-text-wrap\">\n\n                                        <div class=\"grid-item-subtitle\">0 Property<\/div>\n                    \n                                        <div class=\"grid-item-title\">Laguna Grande<\/div>\n                                        \n                                    <\/div><!-- taxonomy-text-wrap -->\n            <\/a>\n        <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-571ff71 animated-slow elementor-invisible elementor-widget elementor-widget-Houzez_elementor_grid_builder\" data-id=\"571ff71\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"Houzez_elementor_grid_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"grid-item  grid-item-v3\" style=\"background-image: url(https:\/\/globoplus.com\/cl\/wp-includes\/images\/media\/default.svg)\">\n            <a class=\"grid-item-link hover-effect-flat\"  href=\"https:\/\/globoplus.com\/cl\/index.php\/property-type\/single-family-home\/\">\n                <div class=\"grid-item-text-wrap\">\n\n                                        <div class=\"grid-item-subtitle\">0 Property<\/div>\n                    \n                                        <div class=\"grid-item-title\">Casa<\/div>\n                                        \n                                    <\/div><!-- taxonomy-text-wrap -->\n            <\/a>\n        <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3a780b3\" data-id=\"3a780b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca10294 animated-slow elementor-invisible elementor-widget elementor-widget-Houzez_elementor_grid_builder\" data-id=\"ca10294\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"Houzez_elementor_grid_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"grid-item  grid-item-v3\" style=\"background-image: url(https:\/\/globoplus.com\/cl\/wp-includes\/images\/media\/default.svg)\">\n            <a class=\"grid-item-link hover-effect-flat\"  href=\"https:\/\/globoplus.com\/cl\/index.php\/property-type\/apartment\/\">\n                <div class=\"grid-item-text-wrap\">\n\n                                        <div class=\"grid-item-subtitle\">3 Properties<\/div>\n                    \n                                        <div class=\"grid-item-title\">Departamento<\/div>\n                                        \n                                    <\/div><!-- taxonomy-text-wrap -->\n            <\/a>\n        <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0898fee animated-slow elementor-invisible elementor-widget elementor-widget-Houzez_elementor_grid_builder\" data-id=\"0898fee\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"Houzez_elementor_grid_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"grid-item  grid-item-v2\" style=\"background-image: url(https:\/\/globoplus.com\/cl\/wp-includes\/images\/media\/default.svg)\">\n            <a class=\"grid-item-link hover-effect-flat\"  href=\"https:\/\/globoplus.com\/cl\/index.php\/property-type\/villa\/\">\n                <div class=\"grid-item-text-wrap\">\n\n                                        <div class=\"grid-item-subtitle\">0 Property<\/div>\n                    \n                                        <div class=\"grid-item-title\">Condominio<\/div>\n                                        \n                                    <\/div><!-- taxonomy-text-wrap -->\n            <\/a>\n        <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-130be45\" data-id=\"130be45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b5da73 animated-slow elementor-invisible elementor-widget elementor-widget-Houzez_elementor_grid_builder\" data-id=\"3b5da73\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"Houzez_elementor_grid_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"grid-item  grid-item-v2\" style=\"background-image: url(https:\/\/globoplus.com\/cl\/wp-includes\/images\/media\/default.svg)\">\n            <a class=\"grid-item-link hover-effect-flat\"  href=\"https:\/\/globoplus.com\/cl\/index.php\/area\/luque\/\">\n                <div class=\"grid-item-text-wrap\">\n\n                                        <div class=\"grid-item-subtitle\">0 Property<\/div>\n                    \n                                        <div class=\"grid-item-title\">Luque<\/div>\n                                        \n                                    <\/div><!-- taxonomy-text-wrap -->\n            <\/a>\n        <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b30ffca animated-slow elementor-invisible elementor-widget elementor-widget-Houzez_elementor_grid_builder\" data-id=\"b30ffca\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"Houzez_elementor_grid_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"grid-item  grid-item-v2\" style=\"background-image: url(https:\/\/globoplus.com\/cl\/wp-includes\/images\/media\/default.svg)\">\n            <a class=\"grid-item-link hover-effect-flat\"  href=\"https:\/\/globoplus.com\/cl\/index.php\/area\/villa-morra\/\">\n                <div class=\"grid-item-text-wrap\">\n\n                                        <div class=\"grid-item-subtitle\">0 Property<\/div>\n                    \n                                        <div class=\"grid-item-title\">Villa Morra<\/div>\n                                        \n                                    <\/div><!-- taxonomy-text-wrap -->\n            <\/a>\n        <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-494c4c3 animated-slow elementor-invisible elementor-widget elementor-widget-Houzez_elementor_grid_builder\" data-id=\"494c4c3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"Houzez_elementor_grid_builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"grid-item  grid-item-v2\" style=\"background-image: url(https:\/\/globoplus.com\/cl\/wp-includes\/images\/media\/default.svg)\">\n            <a class=\"grid-item-link hover-effect-flat\"  href=\"https:\/\/globoplus.com\/cl\/index.php\/area\/san-bernardino\/\">\n                <div class=\"grid-item-text-wrap\">\n\n                                        <div class=\"grid-item-subtitle\">0 Property<\/div>\n                    \n                                        <div class=\"grid-item-title\">San Bernardino<\/div>\n                                        \n                                    <\/div><!-- taxonomy-text-wrap -->\n            <\/a>\n        <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe9c6ee elementor-widget elementor-widget-spacer\" data-id=\"fe9c6ee\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51306c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"51306c3\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f93d15b\" data-id=\"f93d15b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08c7914 elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"08c7914\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30f0a18 animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"30f0a18\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Conoce a nuestros agentes<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">Choose from different listing templates and lay them out\u0003as lists or grids, full-width or boxed  \u200b<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7683ac9 elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"7683ac9\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ede30c7\" data-id=\"ede30c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b876508 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b876508\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-389311c\" data-id=\"389311c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8195f17 elementor-widget elementor-widget-houzez_elementor_agents\" data-id=\"8195f17\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_agents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <!--start agents module-->\n        \n            <div class=\"agent-module module-3cols clearfix\">\n\n                <div class=\"agent-item\">\n\t<div class=\"agent-thumb\">\n\t\t<a href=\"https:\/\/globoplus.com\/cl\/index.php\/agent\/samuel-palmer\/\">\n\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-3-150x150.jpg\" class=\"img-fluid rounded-circle wp-post-image\" alt=\"\" srcset=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-3-150x150.jpg 150w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-3-300x300.jpg 300w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-3-600x600.jpg 600w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-3-496x496.jpg 496w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-3.jpg 700w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"agent-info\">\n\t\t<div class=\"agent-name\">\n\t\t\t<a href=\"https:\/\/globoplus.com\/cl\/index.php\/agent\/samuel-palmer\/\"><strong>Samuel Palmer<\/strong><\/a>\n\t\t<\/div>\n\n\t\t<div class=\"agent-company\">\n\t\t\t                Founder &amp; CEO                                , Realty Properties Inc.\n                            \t\t<\/div>\n\t<\/div>\n\t<div class=\"agent-body\">\n\t\tLorem ipsum dolor sit amet, consectetur adipiscing elit. Nullam imperdiet ullamcorper nisl, sed venenatis...\t<\/div>\n\t<div class=\"agent-link\">\n\t\t<a href=\"https:\/\/globoplus.com\/cl\/index.php\/agent\/samuel-palmer\/\">Ver perfil<\/a>\n\t<\/div>\n<\/div><div class=\"agent-item\">\n\t<div class=\"agent-thumb\">\n\t\t<a href=\"https:\/\/globoplus.com\/cl\/index.php\/agent\/vincent-fuller\/\">\n\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-4-150x150.jpg\" class=\"img-fluid rounded-circle wp-post-image\" alt=\"\" srcset=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-4-150x150.jpg 150w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-4-300x300.jpg 300w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-4-496x496.jpg 496w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-4.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"agent-info\">\n\t\t<div class=\"agent-name\">\n\t\t\t<a href=\"https:\/\/globoplus.com\/cl\/index.php\/agent\/vincent-fuller\/\"><strong>Vincent Fuller<\/strong><\/a>\n\t\t<\/div>\n\n\t\t<div class=\"agent-company\">\n\t\t\t                Company Agent                                , Cool Houses Inc.\n                            \t\t<\/div>\n\t<\/div>\n\t<div class=\"agent-body\">\n\t\tLorem ipsum dolor sit amet, consectetur adipiscing elit. Nullam imperdiet ullamcorper nisl, sed venenatis...\t<\/div>\n\t<div class=\"agent-link\">\n\t\t<a href=\"https:\/\/globoplus.com\/cl\/index.php\/agent\/vincent-fuller\/\">Ver perfil<\/a>\n\t<\/div>\n<\/div><div class=\"agent-item\">\n\t<div class=\"agent-thumb\">\n\t\t<a href=\"https:\/\/globoplus.com\/cl\/index.php\/agent\/brittany-watkins\/\">\n\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-2-150x150.jpg\" class=\"img-fluid rounded-circle wp-post-image\" alt=\"\" srcset=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-2-150x150.jpg 150w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-2-300x300.jpg 300w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-2-768x768.jpg 768w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-2-780x780.jpg 780w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-2-600x600.jpg 600w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-2-496x496.jpg 496w, https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2016\/02\/agent-2.jpg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t<\/a>\n\t<\/div>\n\n\t<div class=\"agent-info\">\n\t\t<div class=\"agent-name\">\n\t\t\t<a href=\"https:\/\/globoplus.com\/cl\/index.php\/agent\/brittany-watkins\/\"><strong>Brittany Watkins<\/strong><\/a>\n\t\t<\/div>\n\n\t\t<div class=\"agent-company\">\n\t\t\t                Company Agent                                , Smart Houses Inc.\n                            \t\t<\/div>\n\t<\/div>\n\t<div class=\"agent-body\">\n\t\tLorem ipsum dolor sit amet, consectetur adipiscing elit. Nullam imperdiet ullamcorper nisl, sed venenatis...\t<\/div>\n\t<div class=\"agent-link\">\n\t\t<a href=\"https:\/\/globoplus.com\/cl\/index.php\/agent\/brittany-watkins\/\">Ver perfil<\/a>\n\t<\/div>\n<\/div>            <\/div><!-- agent-module -->\n\n                <!--end post agents module-->\n\n\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57c72e0 elementor-widget elementor-widget-spacer\" data-id=\"57c72e0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7fa22cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7fa22cf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a73d78\" data-id=\"3a73d78\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47ad7a1 elementor-widget elementor-widget-spacer\" data-id=\"47ad7a1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c98ded elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c98ded\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0cf6b1c\" data-id=\"0cf6b1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31224b3 animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"31224b3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">ChatGPT, integrado arm\u00f3nicamente.<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">ChatGPT de OpenAI est\u00e1 integrado en Globo+ y en las Herramientas de GloboChat, para que puedas aprovechar su ayuda sin necesidad de pasar de una herramienta a la otra. GloboChat puede recurrir a ChatGPT para determinadas solicitudes, como preguntas sobre temas legales,  analizar contratos y documentos.<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ecb97ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ecb97ba\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-438afac\" data-id=\"438afac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41e4a75 elementor-widget elementor-widget-spacer\" data-id=\"41e4a75\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-56db738 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56db738\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-89abaef\" data-id=\"89abaef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec991e3 animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"ec991e3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Nuestros servicios<\/h2>\n                \n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1ec493 animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_icon_box\" data-id=\"e1ec493\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"text-with-icons-module module-3cols clearfix\">\n            \n                    <div class=\"text-with-icon-item text-with-icon-item-v2\">\n                        <div class=\"d-flex\">\n                            <div class=\"icon-thumb\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2019\/03\/people.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>                            <\/div><!-- icon-thumb -->\n                            <div class=\"text-with-icon-content-wrap flex-grow-1\">\n                                <div class=\"text-with-icon-info\">\n                                    <div class=\"text-with-icon-title\">\n                                        <strong>Gesti\u00f3n Inmobiliaria<\/strong>\n                                    <\/div><!-- text-with-icon-title -->\n                                    <div class=\"text-with-icon-body\">\n                                        Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy                                          <\/div><!-- text-with-icon-body -->\n                                <\/div><!-- text-with-icon-info -->\n                                \n                                \n                            <\/div><!-- text-with-icon-content-wrap -->\n                        <\/div><!-- d-flex -->\n                    <\/div><!-- text-with-icon-item  -->\n\n            \n                    <div class=\"text-with-icon-item text-with-icon-item-v2\">\n                        <div class=\"d-flex\">\n                            <div class=\"icon-thumb\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2019\/03\/donut-chart-1.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>                            <\/div><!-- icon-thumb -->\n                            <div class=\"text-with-icon-content-wrap flex-grow-1\">\n                                <div class=\"text-with-icon-info\">\n                                    <div class=\"text-with-icon-title\">\n                                        <strong>Manejo de Capitales<\/strong>\n                                    <\/div><!-- text-with-icon-title -->\n                                    <div class=\"text-with-icon-body\">\n                                        Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy                                          <\/div><!-- text-with-icon-body -->\n                                <\/div><!-- text-with-icon-info -->\n                                \n                                \n                            <\/div><!-- text-with-icon-content-wrap -->\n                        <\/div><!-- d-flex -->\n                    <\/div><!-- text-with-icon-item  -->\n\n            \n                    <div class=\"text-with-icon-item text-with-icon-item-v2\">\n                        <div class=\"d-flex\">\n                            <div class=\"icon-thumb\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"59\" height=\"60\" src=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2019\/03\/bar-chart-stats-up.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>                            <\/div><!-- icon-thumb -->\n                            <div class=\"text-with-icon-content-wrap flex-grow-1\">\n                                <div class=\"text-with-icon-info\">\n                                    <div class=\"text-with-icon-title\">\n                                        <strong>Reportes financieros<\/strong>\n                                    <\/div><!-- text-with-icon-title -->\n                                    <div class=\"text-with-icon-body\">\n                                        Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy                                          <\/div><!-- text-with-icon-body -->\n                                <\/div><!-- text-with-icon-info -->\n                                \n                                \n                            <\/div><!-- text-with-icon-content-wrap -->\n                        <\/div><!-- d-flex -->\n                    <\/div><!-- text-with-icon-item  -->\n\n            \n                    <div class=\"text-with-icon-item text-with-icon-item-v2\">\n                        <div class=\"d-flex\">\n                            <div class=\"icon-thumb\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"57\" src=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2019\/03\/shacking-hands.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>                            <\/div><!-- icon-thumb -->\n                            <div class=\"text-with-icon-content-wrap flex-grow-1\">\n                                <div class=\"text-with-icon-info\">\n                                    <div class=\"text-with-icon-title\">\n                                        <strong>Desarrollo de nuevos Negocios<\/strong>\n                                    <\/div><!-- text-with-icon-title -->\n                                    <div class=\"text-with-icon-body\">\n                                        Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy                                          <\/div><!-- text-with-icon-body -->\n                                <\/div><!-- text-with-icon-info -->\n                                \n                                \n                            <\/div><!-- text-with-icon-content-wrap -->\n                        <\/div><!-- d-flex -->\n                    <\/div><!-- text-with-icon-item  -->\n\n            \n                    <div class=\"text-with-icon-item text-with-icon-item-v2\">\n                        <div class=\"d-flex\">\n                            <div class=\"icon-thumb\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2019\/03\/bar-chart-board.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>                            <\/div><!-- icon-thumb -->\n                            <div class=\"text-with-icon-content-wrap flex-grow-1\">\n                                <div class=\"text-with-icon-info\">\n                                    <div class=\"text-with-icon-title\">\n                                        <strong>Finance Real Estate<\/strong>\n                                    <\/div><!-- text-with-icon-title -->\n                                    <div class=\"text-with-icon-body\">\n                                        Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy                                          <\/div><!-- text-with-icon-body -->\n                                <\/div><!-- text-with-icon-info -->\n                                \n                                \n                            <\/div><!-- text-with-icon-content-wrap -->\n                        <\/div><!-- d-flex -->\n                    <\/div><!-- text-with-icon-item  -->\n\n            \n                    <div class=\"text-with-icon-item text-with-icon-item-v2\">\n                        <div class=\"d-flex\">\n                            <div class=\"icon-thumb\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"54\" src=\"https:\/\/globoplus.com\/cl\/wp-content\/uploads\/2019\/03\/balance.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/>                            <\/div><!-- icon-thumb -->\n                            <div class=\"text-with-icon-content-wrap flex-grow-1\">\n                                <div class=\"text-with-icon-info\">\n                                    <div class=\"text-with-icon-title\">\n                                        <strong>Asistencia Legal<\/strong>\n                                    <\/div><!-- text-with-icon-title -->\n                                    <div class=\"text-with-icon-body\">\n                                        Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy                                          <\/div><!-- text-with-icon-body -->\n                                <\/div><!-- text-with-icon-info -->\n                                \n                                \n                            <\/div><!-- text-with-icon-content-wrap -->\n                        <\/div><!-- d-flex -->\n                    <\/div><!-- text-with-icon-item  -->\n\n                    <\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-11ac4e7 elementor-widget elementor-widget-spacer\" data-id=\"11ac4e7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-684e52a elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"684e52a\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dc3cd0a\" data-id=\"dc3cd0a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94f9f44 elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"94f9f44\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bde267e animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"bde267e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Updates From Our blog<\/h2>\n                \n                                    <p class=\"houzez_section_subtitle\">Choose from different listing templates and lay them out\u0003as lists or grids, full-width or boxed  \u200b<\/p>\n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d93428 elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"6d93428\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-284a97f\" data-id=\"284a97f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf4214f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf4214f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a0366f\" data-id=\"2a0366f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4680854 elementor-widget elementor-widget-houzez_elementor_blog_posts\" data-id=\"4680854\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_blog_posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"blog-posts-module blog-posts-module-v1\">\n            <div class=\"row module-row\">\n                            <\/div>\n        <\/div>\n\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-854cbfd elementor-widget elementor-widget-houzez_elementor_space\" data-id=\"854cbfd\" data-element_type=\"widget\" data-widget_type=\"houzez_elementor_space.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"houzez-spacer\">\n            <div class=\"houzez-spacer-inner\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9ff62b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9ff62b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff6240a\" data-id=\"ff6240a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f1844dd elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1844dd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6902ce0\" data-id=\"6902ce0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d33890 animated-slow elementor-invisible elementor-widget elementor-widget-houzez_elementor_section_title\" data-id=\"7d33890\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"houzez_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"houzez_section_title_wrap section-title-module\">\n                                    <h2 class=\"houzez_section_title\">Newsletter Sing Up<\/h2>\n                \n                            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9f9e4f1\" data-id=\"9f9e4f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5f2e5e elementor-widget elementor-widget-shortcode\" data-id=\"e5f2e5e\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script>(function() {\n\twindow.mc4wp = window.mc4wp || {\n\t\tlisteners: [],\n\t\tforms: {\n\t\t\ton: function(evt, cb) {\n\t\t\t\twindow.mc4wp.listeners.push(\n\t\t\t\t\t{\n\t\t\t\t\t\tevent   : evt,\n\t\t\t\t\t\tcallback: cb\n\t\t\t\t\t}\n\t\t\t\t);\n\t\t\t}\n\t\t}\n\t}\n})();\n<\/script><!-- Mailchimp for WordPress v4.10.6 - https:\/\/wordpress.org\/plugins\/mailchimp-for-wp\/ --><form id=\"mc4wp-form-1\" class=\"mc4wp-form mc4wp-form-1251\" method=\"post\" data-id=\"1251\" data-name=\"Footer Form\" ><div class=\"mc4wp-form-fields\"><div class=\"row\">\n  <div class=\"col-8\">\n    <div class=\"form-group mb-0\">\n      <div class=\"input-email input-icon\">\n        <input class=\"form-control\" type=\"email\" name=\"EMAIL\" required placeholder=\"Enter your email\">\n      <\/div>\n    <\/div>\n  <\/div>\n  <div class=\"col-4\">\n    <div class=\"form-group mb-0\">\n      <button type=\"submit\" class=\"btn btn-primary btn-block\">Submit<\/button>\n    <\/div>\n  <\/div>\n<\/div>\n<\/div><label style=\"display: none !important;\">Deja vac\u00edo este campo si eres humano: <input type=\"text\" name=\"_mc4wp_honeypot\" value=\"\" tabindex=\"-1\" autocomplete=\"off\" \/><\/label><input type=\"hidden\" name=\"_mc4wp_timestamp\" value=\"1778673117\" \/><input type=\"hidden\" name=\"_mc4wp_form_id\" value=\"1251\" \/><input type=\"hidden\" name=\"_mc4wp_form_element_id\" value=\"mc4wp-form-1\" \/><div class=\"mc4wp-response\"><\/div><\/form><!-- \/ Mailchimp for WordPress Plugin --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6c4fd0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6c4fd0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aef1b16\" data-id=\"aef1b16\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c6ef1f elementor-widget elementor-widget-html\" data-id=\"9c6ef1f\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\n  document.getElementById('toggle-chatbot').addEventListener('click', function() {\n    if (window.botpress) {\n      if (window.botpress.open()) {\n        window.botpress.close();\n      } else {\n        window.window.botpress.open();\n      }\n    }\n  });\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Simplificamos la b\u00fasqueda de tu nuevo hogar Transform\u00e1ndola en una experiencia simple y libre de estr\u00e9s. \u00bfEn qu\u00e9 te podemos ayudar hoy? Abrir GloboChat All En Arriendo En Venta Barrios BarriosLaguna GrandeLuqueSan BernardinoSan LorenzoVilla MorraYkua Sati Palabra clave Buscar Propiedades Destacadas Descubre los proyectos inmobiliarios en Paraguay donde tu inversi\u00f3n crece con seguridad, transparencia y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-194","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/globoplus.com\/cl\/index.php\/wp-json\/wp\/v2\/pages\/194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globoplus.com\/cl\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/globoplus.com\/cl\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/globoplus.com\/cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globoplus.com\/cl\/index.php\/wp-json\/wp\/v2\/comments?post=194"}],"version-history":[{"count":233,"href":"https:\/\/globoplus.com\/cl\/index.php\/wp-json\/wp\/v2\/pages\/194\/revisions"}],"predecessor-version":[{"id":4546,"href":"https:\/\/globoplus.com\/cl\/index.php\/wp-json\/wp\/v2\/pages\/194\/revisions\/4546"}],"wp:attachment":[{"href":"https:\/\/globoplus.com\/cl\/index.php\/wp-json\/wp\/v2\/media?parent=194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}